{"id":12967,"date":"2025-06-09T21:17:26","date_gmt":"2025-06-09T21:17:26","guid":{"rendered":"https:\/\/pregnancyoptions.spence-chapin.org\/?post_type=families&#038;p=12967"},"modified":"2026-02-03T20:26:27","modified_gmt":"2026-02-03T20:26:27","slug":"jimmy-josue","status":"publish","type":"families","link":"https:\/\/pregnancyoptions.spence-chapin.org\/es\/families\/jimmy-josue\/","title":{"rendered":"Jimmy y Josu\u00e9"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Somos Jimmy y Josu\u00e9. Empezamos a salir mientras estudi\u00e1bamos en la universidad en 2016 y estamos casados desde 2019. En 2021, a\u00f1adimos a nuestra familia un adorable yorkshire terrier llamado Diego. Empezamos a hablar de tener hijos antes de casarnos y estamos emocionados de ampliar nuestra familia mediante la adopci\u00f3n ahora que estamos en una etapa estable de nuestras vidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somos de diferentes razas y etnias, hablamos distintos idiomas y tenemos diferentes formaciones (Jimmy estudi\u00f3 matem\u00e1ticas y neurociencia; Josu\u00e9, trabajo social y educaci\u00f3n superior). Gracias a nuestros diferentes or\u00edgenes, nos inspiramos mutuamente a comprender el mundo de nuevas maneras. En esencia, somos personas cari\u00f1osas, atentas y emp\u00e1ticas. Creemos que nuestras diferencias y similitudes nos ayudar\u00e1n a crear un hogar acogedor y amoroso a medida que nuestra familia crece.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Acerca de Jimmy:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Photo-768x1024.jpg\" alt=\"\" class=\"wp-image-12968\" style=\"width:479px;height:auto\" srcset=\"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Photo-768x1024.jpg 768w, https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Photo-225x300.jpg 225w, https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Photo-1152x1536.jpg 1152w, https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Photo-scaled.jpg 1200w, https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Photo-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Descripci\u00f3n del puesto: Vicepresidente de una empresa multinacional de gesti\u00f3n de inversiones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pasatiempos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Actividades al aire libre (por ejemplo, correr, nadar y hacer senderismo)<\/li>\n\n\n\n<li>Ver anime y leer manga<\/li>\n\n\n\n<li>Visita a museos de arte y ciencia<\/li>\n\n\n\n<li>Aprender sobre diferentes culturas (por ejemplo, viajando y aprendiendo idiomas)<\/li>\n\n\n\n<li>Tocar instrumentos musicales (por ejemplo, el erhu\/viol\u00edn chino)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dato curioso: La lengua materna de Jimmy es el chino mandar\u00edn, y habla ingl\u00e9s con fluidez, tiene facilidad de conversaci\u00f3n en japon\u00e9s y \u00a1actualmente est\u00e1 aprendiendo espa\u00f1ol! Tambi\u00e9n planea aprender lenguaje de se\u00f1as americano.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Acerca de Josu\u00e9:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Josue-Photo-768x1024.jpg\" alt=\"\" class=\"wp-image-12969\" style=\"width:596px;height:auto\" srcset=\"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Josue-Photo-768x1024.jpg 768w, https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Josue-Photo-225x300.jpg 225w, https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Josue-Photo-1152x1536.jpg 1152w, https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Josue-Photo-scaled.jpg 1200w, https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Josue-Photo-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Descripci\u00f3n del puesto: Presidente\/CEO de una empresa de desarrollo inmobiliario<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pasatiempos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ir a espect\u00e1culos de Broadway<\/li>\n\n\n\n<li>Senderismo y acampada<\/li>\n\n\n\n<li>Explorando zool\u00f3gicos y acuarios (especialmente encuentros con animales y recorridos detr\u00e1s de escena)<\/li>\n\n\n\n<li>Cantando karaoke<\/li>\n\n\n\n<li>Viajar (especialmente a nivel internacional)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dato curioso: A Josu\u00e9 le encanta cocinar y prepara una frittata espectacular, costillas que se deshacen en el hueso y deliciosas galletas de chocolate y canela. Tambi\u00e9n le encanta probar diferentes restaurantes, tanto en casa como de viaje.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Nuestras vidas:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Jimmy trabaja a tiempo completo, pero solo est\u00e1 en la oficina tres d\u00edas a la semana, mientras que Josu\u00e9 tiene su propio horario y trabaja principalmente desde casa. Esto significa que podemos pasar mucho tiempo de calidad juntos en casa, en las comunidades a las que pertenecemos y mientras viajamos por el mundo. Nos encanta ir a obras de Broadway, visitar museos y explorar zool\u00f3gicos, sobre todo disfrutando de las visitas entre bastidores y los encuentros con animales. Tambi\u00e9n llevamos una vida activa: vamos al gimnasio, sacamos a pasear a nuestro perro, Diego, y jugamos al tenis de mesa varias veces a la semana. A Diego le encanta el tenis de mesa; \u00a1est\u00e1 obsesionado con perseguir las pelotas de ping pong!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra pasi\u00f3n por viajar y explorar la cultura es una parte importante de nuestras vidas. Nos encanta aprender sobre gastronom\u00eda, arte, idiomas, historia y mucho m\u00e1s. Adem\u00e1s de ingl\u00e9s, planeamos ense\u00f1arle espa\u00f1ol y chino mandar\u00edn, nuestras lenguas maternas, a trav\u00e9s de libros, programas de televisi\u00f3n e interacciones cotidianas. Tambi\u00e9n queremos fomentar su individualidad anim\u00e1ndolo a explorar su herencia y descubrir sus pasiones, ya sean deportes, artes o cualquier otra \u00e1rea. Estamos ansiosos por compartir nuestras pasiones con nuestro futuro hijo y nos entusiasma aprender lo que disfruta para poder incorporarlo tambi\u00e9n a nuestras vidas.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Nuestra Familia:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Jimmy es hijo \u00fanico y creci\u00f3 en China (su primer viaje internacional fue a Estados Unidos para asistir a la universidad, cuando ten\u00eda 17 a\u00f1os). Sus padres viven en Shangh\u00e1i y viaja con regularidad para visitarlos, as\u00ed como a sus abuelos. Los padres de Jimmy tambi\u00e9n vienen a Estados Unidos aproximadamente una vez al a\u00f1o y cocinan deliciosa comida china.<br>\u00a1Comida cuando est\u00e1n aqu\u00ed! Jimmy y sus padres tambi\u00e9n se mantienen en contacto por videollamadas semanales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Josu\u00e9 es el pen\u00faltimo de cinco hermanos, naci\u00f3 en Michigan y se crio tanto en Michigan como en Puerto Rico. Sus padres, junto con sus hermanos, sobrinos y sobrinas, a\u00fan viven en Michigan, y \u00e9l los visita varias veces al a\u00f1o. Tambi\u00e9n lo han visitado muchas veces mientras Josu\u00e9 viv\u00eda en Chicago, el \u00e1rea de la Bah\u00eda de San Francisco y ahora el \u00e1rea de la ciudad de Nueva York. Cuando est\u00e1n juntos, las interacciones familiares a menudo giran en torno a la preparaci\u00f3n y el disfrute de comidas deliciosas, desde carnes a la parrilla hasta arroz puertorrique\u00f1o y...<br>postres horneados<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Reflexiones finales:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos que nuestro perfil refleje nuestra ilusi\u00f3n por formar una familia mediante la adopci\u00f3n. No sabemos c\u00f3mo ser\u00e1 tomar esta decisi\u00f3n como madre biol\u00f3gica, pero queremos que sepas que te estaremos eternamente agradecidas por confiar en nosotras. Honraremos tu decisi\u00f3n de ayudarnos a formar una familia, esforz\u00e1ndonos por brindarte amor y apoyo incondicionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u2013 Jimmy y Josu\u00e9<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"featured_media":12970,"template":"","class_list":["post-12967","families","type-families","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jimmy &amp; Josu\u00e9 - Your Pregnancy Choices<\/title>\n<meta name=\"description\" content=\"We are Jimmy and Josu\u00e9. We started dating while in grad school in 2016 and have been married since 2019. In 2021, we added an adorable Yorkie named Diego to our family. We started discussing having kids before we married, and are excited to grow our family through adoption now that we are in a stable stage of our lives.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pregnancyoptions.spence-chapin.org\/es\/families\/jimmy-josue\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jimmy &amp; Josu\u00e9 - Your Pregnancy Choices\" \/>\n<meta property=\"og:description\" content=\"We are Jimmy and Josu\u00e9. We started dating while in grad school in 2016 and have been married since 2019. In 2021, we added an adorable Yorkie named Diego to our family. We started discussing having kids before we married, and are excited to grow our family through adoption now that we are in a stable stage of our lives.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pregnancyoptions.spence-chapin.org\/es\/families\/jimmy-josue\/\" \/>\n<meta property=\"og:site_name\" content=\"Your Pregnancy Choices\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T20:26:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Josue-Cover-Photo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"899\" \/>\n\t<meta property=\"og:image:height\" content=\"1199\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/families\\\/jimmy-josue\\\/\",\"url\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/families\\\/jimmy-josue\\\/\",\"name\":\"Jimmy &amp; Josu\u00e9 - Your Pregnancy Choices\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yourpregnancychoices.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/families\\\/jimmy-josue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/families\\\/jimmy-josue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Jimmy-Josue-Cover-Photo.jpg\",\"datePublished\":\"2025-06-09T21:17:26+00:00\",\"dateModified\":\"2026-02-03T20:26:27+00:00\",\"description\":\"We are Jimmy and Josu\u00e9. We started dating while in grad school in 2016 and have been married since 2019. In 2021, we added an adorable Yorkie named Diego to our family. We started discussing having kids before we married, and are excited to grow our family through adoption now that we are in a stable stage of our lives.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/families\\\/jimmy-josue\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/families\\\/jimmy-josue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/families\\\/jimmy-josue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Jimmy-Josue-Cover-Photo.jpg\",\"contentUrl\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Jimmy-Josue-Cover-Photo.jpg\",\"width\":899,\"height\":1199},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/families\\\/jimmy-josue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jimmy &amp; Josu\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yourpregnancychoices.org\\\/#website\",\"url\":\"https:\\\/\\\/yourpregnancychoices.org\\\/\",\"name\":\"Your Pregnancy Choices\",\"description\":\"If you are pregnant and unsure of what to do, explore your options here.\",\"publisher\":{\"@id\":\"https:\\\/\\\/yourpregnancychoices.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yourpregnancychoices.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yourpregnancychoices.org\\\/#organization\",\"name\":\"Your Pregnancy Choices\",\"url\":\"https:\\\/\\\/yourpregnancychoices.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/yourpregnancychoices.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/cropped-SpenceChapin-Logo-FINAL_Primary-TaglineGeneral-FullColor.png\",\"contentUrl\":\"https:\\\/\\\/pregnancyoptions.spence-chapin.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/cropped-SpenceChapin-Logo-FINAL_Primary-TaglineGeneral-FullColor.png\",\"width\":1207,\"height\":255,\"caption\":\"Your Pregnancy Choices\"},\"image\":{\"@id\":\"https:\\\/\\\/yourpregnancychoices.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jimmy y Josu\u00e9: Tus opciones durante el embarazo","description":"Somos Jimmy y Josu\u00e9. Empezamos a salir mientras estudi\u00e1bamos en la universidad en 2016 y estamos casados desde 2019. En 2021, a\u00f1adimos a nuestra familia un adorable yorkshire terrier llamado Diego. Empezamos a hablar de tener hijos antes de casarnos y estamos emocionados de ampliar nuestra familia mediante la adopci\u00f3n ahora que estamos en una etapa estable de nuestras vidas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pregnancyoptions.spence-chapin.org\/es\/families\/jimmy-josue\/","og_locale":"es_MX","og_type":"article","og_title":"Jimmy &amp; Josu\u00e9 - Your Pregnancy Choices","og_description":"We are Jimmy and Josu\u00e9. We started dating while in grad school in 2016 and have been married since 2019. In 2021, we added an adorable Yorkie named Diego to our family. We started discussing having kids before we married, and are excited to grow our family through adoption now that we are in a stable stage of our lives.","og_url":"https:\/\/pregnancyoptions.spence-chapin.org\/es\/families\/jimmy-josue\/","og_site_name":"Your Pregnancy Choices","article_modified_time":"2026-02-03T20:26:27+00:00","og_image":[{"width":899,"height":1199,"url":"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Josue-Cover-Photo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pregnancyoptions.spence-chapin.org\/families\/jimmy-josue\/","url":"https:\/\/pregnancyoptions.spence-chapin.org\/families\/jimmy-josue\/","name":"Jimmy y Josu\u00e9: Tus opciones durante el embarazo","isPartOf":{"@id":"https:\/\/yourpregnancychoices.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pregnancyoptions.spence-chapin.org\/families\/jimmy-josue\/#primaryimage"},"image":{"@id":"https:\/\/pregnancyoptions.spence-chapin.org\/families\/jimmy-josue\/#primaryimage"},"thumbnailUrl":"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Josue-Cover-Photo.jpg","datePublished":"2025-06-09T21:17:26+00:00","dateModified":"2026-02-03T20:26:27+00:00","description":"Somos Jimmy y Josu\u00e9. Empezamos a salir mientras estudi\u00e1bamos en la universidad en 2016 y estamos casados desde 2019. En 2021, a\u00f1adimos a nuestra familia un adorable yorkshire terrier llamado Diego. Empezamos a hablar de tener hijos antes de casarnos y estamos emocionados de ampliar nuestra familia mediante la adopci\u00f3n ahora que estamos en una etapa estable de nuestras vidas.","breadcrumb":{"@id":"https:\/\/pregnancyoptions.spence-chapin.org\/families\/jimmy-josue\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pregnancyoptions.spence-chapin.org\/families\/jimmy-josue\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/pregnancyoptions.spence-chapin.org\/families\/jimmy-josue\/#primaryimage","url":"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Josue-Cover-Photo.jpg","contentUrl":"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2025\/06\/Jimmy-Josue-Cover-Photo.jpg","width":899,"height":1199},{"@type":"BreadcrumbList","@id":"https:\/\/pregnancyoptions.spence-chapin.org\/families\/jimmy-josue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pregnancyoptions.spence-chapin.org\/"},{"@type":"ListItem","position":2,"name":"Jimmy &amp; Josu\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/yourpregnancychoices.org\/#website","url":"https:\/\/yourpregnancychoices.org\/","name":"Sus opciones durante el embarazo","description":"Si est\u00e1 embarazada y no est\u00e1 segura de qu\u00e9 hacer, explore sus opciones aqu\u00ed.","publisher":{"@id":"https:\/\/yourpregnancychoices.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yourpregnancychoices.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/yourpregnancychoices.org\/#organization","name":"Sus opciones durante el embarazo","url":"https:\/\/yourpregnancychoices.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/yourpregnancychoices.org\/#\/schema\/logo\/image\/","url":"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2019\/10\/cropped-SpenceChapin-Logo-FINAL_Primary-TaglineGeneral-FullColor.png","contentUrl":"https:\/\/pregnancyoptions.spence-chapin.org\/wp-content\/uploads\/2019\/10\/cropped-SpenceChapin-Logo-FINAL_Primary-TaglineGeneral-FullColor.png","width":1207,"height":255,"caption":"Your Pregnancy Choices"},"image":{"@id":"https:\/\/yourpregnancychoices.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pregnancyoptions.spence-chapin.org\/es\/wp-json\/wp\/v2\/families\/12967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pregnancyoptions.spence-chapin.org\/es\/wp-json\/wp\/v2\/families"}],"about":[{"href":"https:\/\/pregnancyoptions.spence-chapin.org\/es\/wp-json\/wp\/v2\/types\/families"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pregnancyoptions.spence-chapin.org\/es\/wp-json\/wp\/v2\/media\/12970"}],"wp:attachment":[{"href":"https:\/\/pregnancyoptions.spence-chapin.org\/es\/wp-json\/wp\/v2\/media?parent=12967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}